{"id":4200,"date":"2014-10-25T13:21:30","date_gmt":"2014-10-25T11:21:30","guid":{"rendered":"https:\/\/www.kolja-engelmann.de\/blog\/?p=4200"},"modified":"2014-11-09T12:47:23","modified_gmt":"2014-11-09T11:47:23","slug":"thule-perspektiv-daypack-kleiner-kamerarucksack-fuer-die-stadt","status":"publish","type":"post","link":"https:\/\/www.kolja-engelmann.de\/blog\/2014\/10\/thule-perspektiv-daypack-kleiner-kamerarucksack-fuer-die-stadt\/","title":{"rendered":"Thule Perspektiv Daypack &#8211; Kleiner Kamerarucksack f\u00fcr die Stadt"},"content":{"rendered":"<p>Mit Rucks\u00e4cken ist das\u00a0bei mir so wie mit Frauen und Handtaschen: Ich kann nicht genug haben und bin rastlos auf der Suche nach neuen, besseren Modellen. F\u00fcr den Bereich &#8222;Outdoor &#8211;\u00a0Tagestouren&#8220; bin ich mit meinem<a title=\"ClikElite und Pacsafe \u2013 Zwei Kamerarucks\u00e4cke getestet\" href=\"https:\/\/www.kolja-engelmann.de\/blog\/2013\/07\/kamerarucksacke-getestet\/\"> ClikElite Contrejour 35<\/a>\u00a0perfekt ausgestattet.\u00a0Gehe ich jedoch auf St\u00e4dtetour, dann ist der Contrejour 35 einfach \u00fcberdimensioniert. Ich suche nach\u00a0einem stylishen Kamerarucksack, der nicht nach Wanderrucksack aussieht, eine ~60-40 Aufteilung besitzt, so dass man auch mal eine Jacke im &#8222;Daypack&#8220; unterbringen kann, idealerweise ein seitlichen Zugriff auf das Kamerafach gew\u00e4hrt und nat\u00fcrlich meine Ausr\u00fcstung aufnimmt. Dazu geh\u00f6ren\u00a0meine Canon 6D mit angesetztem 70-200mm Objektiv, ein bis zwei weiteren Objektiven, einem Blitz \u00a0und einem kleinen Stativ.<\/p>\n<div id=\"attachment_4201\" style=\"width: 390px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4201\" class=\"size-large wp-image-4201\" src=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1-380x500.jpg\" alt=\"Thule Perspektiv Daypack\" width=\"380\" height=\"500\" srcset=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1-380x500.jpg 380w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1-228x300.jpg 228w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1-720x947.jpg 720w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1.jpg 1140w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a><p id=\"caption-attachment-4201\" class=\"wp-caption-text\">Thule Perspektiv Daypack<\/p><\/div>\n<p>Vor einigen Tagen fand ich im Chip Foto-Video\u00a0Magazin einen Testbericht zum\u00a0&#8222;<a href=\"http:\/\/www.amazon.de\/dp\/B00APQM1GU\/?tag=dragonslayer-21\" target=\"_blank\">Thule Perspektiv Daypack<\/a>&#8222;, der mich optisch sehr ansprach und zumindest auf dem Papier meinen Anforderungen entsprach. Zwei Tage Lieferzeit und ~150\u20ac sp\u00e4ter stand\u00a0der Rucksack\u00a0vor mir und wollte bef\u00fcllt werden. Leider musste ich sofort feststellen, dass der Tester mit dem versprochenen Platz doch etwas \u00fcbertrieben hatte. In das Kamerafach (welches man auch komplett herausnehmen kann) passt h\u00f6chstens\u00a0ein Probody mit angesetztem 24-70mm Objektiv und ein bis zwei sehr kleine Festbrennweiten. Zoomobjektive &#8211; wom\u00f6glich mit \u00fcbergest\u00fclpter Streulichtblende &#8211; finden kaum Platz. Mein 70-200 Zoomobjektiv musste ich deswegen oben im versteiften (und ebenfalls entnehmbaren ) Deckelfach unterbringen, wo es munter hin und her rollte. Das geht, ist aber nicht wirklich optimal.<\/p>\n<div id=\"attachment_4203\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-oberes-fach.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4203\" class=\"size-large wp-image-4203\" src=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-oberes-fach-500x333.jpg\" alt=\"In das obere Fach passt zur Not das 70-200mm Zoom Objektiv\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-oberes-fach-500x333.jpg 500w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-oberes-fach-300x200.jpg 300w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-oberes-fach-720x480.jpg 720w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-oberes-fach.jpg 1500w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-4203\" class=\"wp-caption-text\">In das obere Fach passt zur Not das 70-200mm Zoom Objektiv<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Bereits vorab las ich, dass der Thule auf Grund seiner Ma\u00dfe von (HxBxT)\u00a050cm x 26,9cm x\u00a022.6cm auf dem R\u00fccken von Menschen ab 1,90m etwas zierlich wirkt. Das kann ich best\u00e4tigen, gefiel\u00a0mir aber ganz gut. Ungl\u00fccklich hingegen ist die Positionierung des Beckengurts, der bei mir eher als Bauchgurt fungierte und kaum Gewicht von den Schultern auf die H\u00fcfte verlagerte. Das k\u00f6nnte man vielleicht vernachl\u00e4ssigen, denn wirklich viel Ausr\u00fcstung bekommt man ja eh nicht hinein. So ist es dann auch zu verschmerzen und vermutlich der Gewichtsreduzierung geschuldet, dass die Schnallen von Brust-, Beckengurt und Stativhalterung allesamt sehr klein und instabil wirken und sich selbst mit d\u00fcnnen Handschuhen nicht ohne Gefummel\u00a0\u00f6ffnen oder schlie\u00dfen lassen. Die \u00fcberstehenden Enden der (viel zu schmalen)\u00a0Gurte kann man stets irgendwo verstauen, so dass sie nicht hin und her baumeln. Gerade die Gurte f\u00fcr Beckengurt und Stativhalterung sind jedoch leider etwas kurz geraten, so dass ich sie \u00fcber meiner Wintermontur ordentlich ziehen musste und man volumin\u00f6sere Stative ebenfalls nur mit Fummelei au\u00dfen befestigen kann.<\/p>\n<div id=\"attachment_4202\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-clips.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-4202\" class=\"size-large wp-image-4202\" src=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-clips-500x333.jpg\" alt=\"Vergleich der Schnallengr\u00f6\u00dfe - Vorne Thule Perspektiv Daypack, hinten ClickElite Contrejour 35\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-clips-500x333.jpg 500w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-clips-300x200.jpg 300w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-clips-720x480.jpg 720w, https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-clips.jpg 1500w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-4202\" class=\"wp-caption-text\">Vergleich der Schnallengr\u00f6\u00dfe &#8211; Vorne Thule Perspektiv Daypack, hinten ClickElite Contrejour 35<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Den leichten finnischen Nieselregen der letzten Woche hat der Rucksack jedoch gut weggesteckt. Das Au\u00dfenmaterial wirkt sehr robust, wasser- und schmutzabweisend und alle Rei\u00dfverschl\u00fcsse sind mit einer Gummilippe abgedichtet, so dass ich mir keine Sorgen um eindringende N\u00e4sse zu machen brauche. Nat\u00fcrlich werden\u00a0dadurch die Verschl\u00fcsse etwas schwerg\u00e4ngiger sind und bleiben des \u00f6fteren h\u00e4ngen.<\/p>\n<h3>Fazit<\/h3>\n<p>&#8222;Form follows function&#8220; sagt man ja so gerne. H\u00e4tte ich mich mal nicht davon blenden lassen, dass mir der Thule optisch so gut gef\u00e4llt, dann w\u00e4re mir aufgefallen, dass die Innenabma\u00dfe lediglich f\u00fcr Systemkameras oder spiegellose Systeme ausreichend dimensioniert sind und der Rucksack eher meiner Frau als mir passen w\u00fcrde. Auch die Verschl\u00fcsse und Gurte h\u00e4tten ruhig etwas gr\u00f6\u00dferer sein k\u00f6nnen. Ein\u00a0paar Gramm mehr h\u00e4tten das Gewicht dabei nicht exorbitant anwachsen lassen,\u00a0h\u00e4tten aber mein Gef\u00fchl der Sicherheit f\u00fcr mein Equipment verbessert. W\u00e4re der Thule Perspektiv auch noch\u00a0je 5cm l\u00e4nger und breiter gewesen, so dass auch mein 70-200 Platz gehabt h\u00e4tte, dann h\u00e4tte ich meinen perfekten Stadtrucksack gefunden. So geht er leider zur\u00fcck zum Verk\u00e4ufer und meine Suche nach der perfekten Handtasch- \u00e4h dem perfekten Kamerarucksack geht weiter.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ich suchte nach einem stylishen Kamerarucksack, der nicht nach Wanderrucksack aussieht, eine ~60-40 Aufteilung besitzt, so dass man auch mal eine Jacke im &#8222;Daypack&#8220; unterbringen kann, idealerweise ein seitlichen Zugriff auf das Kamerafach gew\u00e4hrt und nat\u00fcrlich meine Ausr\u00fcstung aufnimmt. Dazu geh\u00f6ren meine Canon 6D mit angesetztem 70-200mm Objektiv, ein bis zwei weiteren Objektiven, einem Blitz  und einem kleinen Stativ. Vielleicht ist es ja der Thule Perspektiv Daypack?<\/p>\n","protected":false},"author":1,"featured_media":4201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[25],"tags":[111],"class_list":["post-4200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-durch-die-linse","tag-photorucksack"],"jetpack_featured_media_url":"https:\/\/www.kolja-engelmann.de\/blog\/wp-content\/uploads\/2014\/10\/thule-perspektiv-daypack-1.jpg","jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/posts\/4200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/comments?post=4200"}],"version-history":[{"count":0,"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/posts\/4200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/media\/4201"}],"wp:attachment":[{"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/media?parent=4200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/categories?post=4200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kolja-engelmann.de\/blog\/wp-json\/wp\/v2\/tags?post=4200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}